{"id":44928,"date":"2023-02-28T07:50:11","date_gmt":"2023-02-28T07:50:11","guid":{"rendered":"https:\/\/www.bonpilates.com\/producto\/corrector-de-pie-355cm\/"},"modified":"2026-05-13T10:16:10","modified_gmt":"2026-05-13T08:16:10","slug":"corrector-de-pie-355cm-2","status":"publish","type":"product","link":"https:\/\/www.bonpilates.com\/nl\/producto\/corrector-de-pie-355cm-2\/","title":{"rendered":"Corrector de pie 35,5cm"},"content":{"rendered":"<p>Primer aparato inventado y patentado por Joseph Pilates, dotado con un pedal, que su creador evolucionar\u00eda hasta la barra de pies del reformer y hasta el pedal de la chair.<br \/>\nEste peque\u00f1o aparato fortalece y eleva el arco del pie, mejora el equilibrio y la marcha. Adem\u00e1s con una buena combinaci\u00f3n de ejercicios influye directamente en el trabajo del tobillo, de la rodilla y de la cadera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Primer aparato inventado y patentado por Joseph Pilates, dotado con un pedal, que su creador evolucionar\u00eda hasta la barra de pies del reformer y hasta el pedal de la chair.<br \/>\nEste peque\u00f1o aparato fortalece y eleva el arco del pie, mejora el equilibrio y la marcha. Adem\u00e1s con una buena combinaci\u00f3n de ejercicios influye directamente en el trabajo del tobillo, de la rodilla y de la cadera<\/p>\n","protected":false},"featured_media":42934,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[997,1001,985],"product_tag":[],"class_list":{"0":"post-44928","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accesorios","7":"product_cat-black-week","8":"product_cat-linea-contemporanea","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Corrector de pie 35,5cm - Bonpilates<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bonpilates.com\/nl\/producto\/corrector-de-pie-355cm-2\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corrector de pie 35,5cm - Bonpilates\" \/>\n<meta property=\"og:description\" content=\"Primer aparato inventado y patentado por Joseph Pilates, dotado con un pedal, que su creador evolucionar\u00eda hasta la barra de pies del reformer y hasta el pedal de la chair. Este peque\u00f1o aparato fortalece y eleva el arco del pie, mejora el equilibrio y la marcha. Adem\u00e1s con una buena combinaci\u00f3n de ejercicios influye directamente en el trabajo del tobillo, de la rodilla y de la cadera\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bonpilates.com\/nl\/producto\/corrector-de-pie-355cm-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonpilates\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bonpilates\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T08:16:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bonpilates.com\/wp-content\/uploads\/2025\/05\/foto-con-menor-calidad-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/producto\\\/corrector-de-pie-355cm-2\\\/\",\"url\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/producto\\\/corrector-de-pie-355cm-2\\\/\",\"name\":\"Corrector de pie 35,5cm - Bonpilates\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/producto\\\/corrector-de-pie-355cm-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/producto\\\/corrector-de-pie-355cm-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bonpilates.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/foto-con-menor-calidad-1.jpg\",\"datePublished\":\"2023-02-28T07:50:11+00:00\",\"dateModified\":\"2026-05-13T08:16:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/producto\\\/corrector-de-pie-355cm-2\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/producto\\\/corrector-de-pie-355cm-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/producto\\\/corrector-de-pie-355cm-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bonpilates.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/foto-con-menor-calidad-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bonpilates.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/foto-con-menor-calidad-1.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/producto\\\/corrector-de-pie-355cm-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Bonpilates\",\"item\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Producten\",\"item\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Corrector de pie 35,5cm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/\",\"name\":\"Bonpilates\",\"description\":\"Desarrollamos y comercializamos m\u00e1quinas de pilates reformer, equipment, accesorios y otros aparatos ideales para practicar este entrenamiento. Bonpilates presenta a sus clientes soluciones de alta calidad y tecnolog\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/#organization\",\"name\":\"Bonpilates\",\"url\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bonpilates.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/bonpilates-logo-header.png\",\"contentUrl\":\"https:\\\/\\\/www.bonpilates.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/bonpilates-logo-header.png\",\"width\":319,\"height\":54,\"caption\":\"Bonpilates\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bonpilates\\\/\",\"https:\\\/\\\/www.instagram.com\\\/bonpilatesspain\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/bonpilates\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corrector de pie 35,5cm - Bonpilates","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bonpilates.com\/nl\/producto\/corrector-de-pie-355cm-2\/","og_locale":"nl_NL","og_type":"article","og_title":"Corrector de pie 35,5cm - Bonpilates","og_description":"Primer aparato inventado y patentado por Joseph Pilates, dotado con un pedal, que su creador evolucionar\u00eda hasta la barra de pies del reformer y hasta el pedal de la chair. Este peque\u00f1o aparato fortalece y eleva el arco del pie, mejora el equilibrio y la marcha. Adem\u00e1s con una buena combinaci\u00f3n de ejercicios influye directamente en el trabajo del tobillo, de la rodilla y de la cadera","og_url":"https:\/\/www.bonpilates.com\/nl\/producto\/corrector-de-pie-355cm-2\/","og_site_name":"Bonpilates","article_publisher":"https:\/\/www.facebook.com\/bonpilates\/","article_modified_time":"2026-05-13T08:16:10+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.bonpilates.com\/wp-content\/uploads\/2025\/05\/foto-con-menor-calidad-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bonpilates.com\/nl\/producto\/corrector-de-pie-355cm-2\/","url":"https:\/\/www.bonpilates.com\/nl\/producto\/corrector-de-pie-355cm-2\/","name":"Corrector de pie 35,5cm - Bonpilates","isPartOf":{"@id":"https:\/\/www.bonpilates.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bonpilates.com\/nl\/producto\/corrector-de-pie-355cm-2\/#primaryimage"},"image":{"@id":"https:\/\/www.bonpilates.com\/nl\/producto\/corrector-de-pie-355cm-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bonpilates.com\/wp-content\/uploads\/2025\/05\/foto-con-menor-calidad-1.jpg","datePublished":"2023-02-28T07:50:11+00:00","dateModified":"2026-05-13T08:16:10+00:00","breadcrumb":{"@id":"https:\/\/www.bonpilates.com\/nl\/producto\/corrector-de-pie-355cm-2\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bonpilates.com\/nl\/producto\/corrector-de-pie-355cm-2\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.bonpilates.com\/nl\/producto\/corrector-de-pie-355cm-2\/#primaryimage","url":"https:\/\/www.bonpilates.com\/wp-content\/uploads\/2025\/05\/foto-con-menor-calidad-1.jpg","contentUrl":"https:\/\/www.bonpilates.com\/wp-content\/uploads\/2025\/05\/foto-con-menor-calidad-1.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.bonpilates.com\/nl\/producto\/corrector-de-pie-355cm-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Bonpilates","item":"https:\/\/www.bonpilates.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Producten","item":"https:\/\/www.bonpilates.com\/nl\/shop\/"},{"@type":"ListItem","position":3,"name":"Corrector de pie 35,5cm"}]},{"@type":"WebSite","@id":"https:\/\/www.bonpilates.com\/nl\/#website","url":"https:\/\/www.bonpilates.com\/nl\/","name":"Bonpilates","description":"Desarrollamos y comercializamos m\u00e1quinas de pilates reformer, equipment, accesorios y otros aparatos ideales para practicar este entrenamiento. Bonpilates presenta a sus clientes soluciones de alta calidad y tecnolog\u00eda.","publisher":{"@id":"https:\/\/www.bonpilates.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bonpilates.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.bonpilates.com\/nl\/#organization","name":"Bonpilates","url":"https:\/\/www.bonpilates.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.bonpilates.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.bonpilates.com\/wp-content\/uploads\/2024\/03\/bonpilates-logo-header.png","contentUrl":"https:\/\/www.bonpilates.com\/wp-content\/uploads\/2024\/03\/bonpilates-logo-header.png","width":319,"height":54,"caption":"Bonpilates"},"image":{"@id":"https:\/\/www.bonpilates.com\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bonpilates\/","https:\/\/www.instagram.com\/bonpilatesspain\/","https:\/\/www.youtube.com\/user\/bonpilates\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.bonpilates.com\/nl\/wp-json\/wp\/v2\/product\/44928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bonpilates.com\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.bonpilates.com\/nl\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bonpilates.com\/nl\/wp-json\/wp\/v2\/media\/42934"}],"wp:attachment":[{"href":"https:\/\/www.bonpilates.com\/nl\/wp-json\/wp\/v2\/media?parent=44928"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.bonpilates.com\/nl\/wp-json\/wp\/v2\/product_brand?post=44928"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.bonpilates.com\/nl\/wp-json\/wp\/v2\/product_cat?post=44928"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.bonpilates.com\/nl\/wp-json\/wp\/v2\/product_tag?post=44928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}