{"id":44961,"date":"2022-07-01T12:12:38","date_gmt":"2022-07-01T12:12:38","guid":{"rendered":"https:\/\/www.bonpilates.com\/producto\/reformer-domus-alto\/"},"modified":"2026-05-13T10:16:22","modified_gmt":"2026-05-13T08:16:22","slug":"reformer-domus-alto","status":"publish","type":"product","link":"https:\/\/www.bonpilates.com\/nl\/producto\/reformer-domus-alto\/","title":{"rendered":"Reformer Domus alto"},"content":{"rendered":"<p style=\"font-weight: 400;\">El Reformer Domus Alto es el reformer con las dimensiones m\u00e1s reducidas pero con la altura de un reformer est\u00e1ndar. Ocupa poco espacio y es muy f\u00e1cil y r\u00e1pido de instalar. El carro es ligero y silencioso y tiene un sistema de seguridad que mantiene el carro sujeto al bastidor cuando lo guardamos en posici\u00f3n vertical.<\/p>\n<p style=\"font-weight: 400;\">El Reformer Domus es el modelo de reformer ideal para las sesiones de pilates en casa y para salas de formaci\u00f3n peque\u00f1as.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Reformer Domus Alto es el reformer con las dimensiones m\u00e1s reducidas pero con la altura de un reformer est\u00e1ndar.<\/p>\n","protected":false},"featured_media":43024,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[985,1014,993],"product_tag":[],"class_list":{"0":"post-44961","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-linea-contemporanea","7":"product_cat-domestico","8":"product_cat-reformer-pilates","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reformer Domus alto - Bonpilates<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bonpilates.com\/nl\/producto\/reformer-domus-alto\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reformer Domus alto - Bonpilates\" \/>\n<meta property=\"og:description\" content=\"El Reformer Domus Alto es el reformer con las dimensiones m\u00e1s reducidas pero con la altura de un reformer est\u00e1ndar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bonpilates.com\/nl\/producto\/reformer-domus-alto\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonpilates\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bonpilates\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T08:16:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bonpilates.com\/wp-content\/uploads\/2025\/05\/81000433-REFORMER-DOMUS-ALTO-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/producto\\\/reformer-domus-alto\\\/\",\"url\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/producto\\\/reformer-domus-alto\\\/\",\"name\":\"Reformer Domus alto - Bonpilates\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/producto\\\/reformer-domus-alto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/producto\\\/reformer-domus-alto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bonpilates.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/81000433-REFORMER-DOMUS-ALTO-1.jpg\",\"datePublished\":\"2022-07-01T12:12:38+00:00\",\"dateModified\":\"2026-05-13T08:16:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/producto\\\/reformer-domus-alto\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/producto\\\/reformer-domus-alto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/producto\\\/reformer-domus-alto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bonpilates.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/81000433-REFORMER-DOMUS-ALTO-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bonpilates.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/81000433-REFORMER-DOMUS-ALTO-1.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/producto\\\/reformer-domus-alto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Bonpilates\",\"item\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Producten\",\"item\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Reformer Domus alto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/\",\"name\":\"Bonpilates\",\"description\":\"Desarrollamos y comercializamos m\u00e1quinas de pilates reformer, equipment, accesorios y otros aparatos ideales para practicar este entrenamiento. Bonpilates presenta a sus clientes soluciones de alta calidad y tecnolog\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/#organization\",\"name\":\"Bonpilates\",\"url\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bonpilates.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/bonpilates-logo-header.png\",\"contentUrl\":\"https:\\\/\\\/www.bonpilates.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/bonpilates-logo-header.png\",\"width\":319,\"height\":54,\"caption\":\"Bonpilates\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bonpilates\\\/\",\"https:\\\/\\\/www.instagram.com\\\/bonpilatesspain\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/bonpilates\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reformer Domus alto - Bonpilates","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bonpilates.com\/nl\/producto\/reformer-domus-alto\/","og_locale":"nl_NL","og_type":"article","og_title":"Reformer Domus alto - Bonpilates","og_description":"El Reformer Domus Alto es el reformer con las dimensiones m\u00e1s reducidas pero con la altura de un reformer est\u00e1ndar.","og_url":"https:\/\/www.bonpilates.com\/nl\/producto\/reformer-domus-alto\/","og_site_name":"Bonpilates","article_publisher":"https:\/\/www.facebook.com\/bonpilates\/","article_modified_time":"2026-05-13T08:16:22+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.bonpilates.com\/wp-content\/uploads\/2025\/05\/81000433-REFORMER-DOMUS-ALTO-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bonpilates.com\/nl\/producto\/reformer-domus-alto\/","url":"https:\/\/www.bonpilates.com\/nl\/producto\/reformer-domus-alto\/","name":"Reformer Domus alto - Bonpilates","isPartOf":{"@id":"https:\/\/www.bonpilates.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bonpilates.com\/nl\/producto\/reformer-domus-alto\/#primaryimage"},"image":{"@id":"https:\/\/www.bonpilates.com\/nl\/producto\/reformer-domus-alto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bonpilates.com\/wp-content\/uploads\/2025\/05\/81000433-REFORMER-DOMUS-ALTO-1.jpg","datePublished":"2022-07-01T12:12:38+00:00","dateModified":"2026-05-13T08:16:22+00:00","breadcrumb":{"@id":"https:\/\/www.bonpilates.com\/nl\/producto\/reformer-domus-alto\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bonpilates.com\/nl\/producto\/reformer-domus-alto\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.bonpilates.com\/nl\/producto\/reformer-domus-alto\/#primaryimage","url":"https:\/\/www.bonpilates.com\/wp-content\/uploads\/2025\/05\/81000433-REFORMER-DOMUS-ALTO-1.jpg","contentUrl":"https:\/\/www.bonpilates.com\/wp-content\/uploads\/2025\/05\/81000433-REFORMER-DOMUS-ALTO-1.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.bonpilates.com\/nl\/producto\/reformer-domus-alto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Bonpilates","item":"https:\/\/www.bonpilates.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Producten","item":"https:\/\/www.bonpilates.com\/nl\/shop\/"},{"@type":"ListItem","position":3,"name":"Reformer Domus alto"}]},{"@type":"WebSite","@id":"https:\/\/www.bonpilates.com\/nl\/#website","url":"https:\/\/www.bonpilates.com\/nl\/","name":"Bonpilates","description":"Desarrollamos y comercializamos m\u00e1quinas de pilates reformer, equipment, accesorios y otros aparatos ideales para practicar este entrenamiento. Bonpilates presenta a sus clientes soluciones de alta calidad y tecnolog\u00eda.","publisher":{"@id":"https:\/\/www.bonpilates.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bonpilates.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.bonpilates.com\/nl\/#organization","name":"Bonpilates","url":"https:\/\/www.bonpilates.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.bonpilates.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.bonpilates.com\/wp-content\/uploads\/2024\/03\/bonpilates-logo-header.png","contentUrl":"https:\/\/www.bonpilates.com\/wp-content\/uploads\/2024\/03\/bonpilates-logo-header.png","width":319,"height":54,"caption":"Bonpilates"},"image":{"@id":"https:\/\/www.bonpilates.com\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bonpilates\/","https:\/\/www.instagram.com\/bonpilatesspain\/","https:\/\/www.youtube.com\/user\/bonpilates\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.bonpilates.com\/nl\/wp-json\/wp\/v2\/product\/44961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bonpilates.com\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.bonpilates.com\/nl\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bonpilates.com\/nl\/wp-json\/wp\/v2\/media\/43024"}],"wp:attachment":[{"href":"https:\/\/www.bonpilates.com\/nl\/wp-json\/wp\/v2\/media?parent=44961"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.bonpilates.com\/nl\/wp-json\/wp\/v2\/product_brand?post=44961"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.bonpilates.com\/nl\/wp-json\/wp\/v2\/product_cat?post=44961"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.bonpilates.com\/nl\/wp-json\/wp\/v2\/product_tag?post=44961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}