{"id":1035,"count":9,"description":"","link":"https:\/\/www.bonpilates.com\/nl\/torres\/","name":"Torres","slug":"torres","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Torres y unidades de pared pilates - Comprar online - Bonpilates<\/title>\n<meta name=\"description\" content=\"Torres y unidades de pared para ejercicios de pilates. Descubre nuestras m\u00e1quinas para pilates y como llegar a un nuevo nivel en pilates.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bonpilates.com\/nl\/torres\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Torres y unidades de pared pilates - Comprar online - Bonpilates\" \/>\n<meta property=\"og:description\" content=\"Torres y unidades de pared para ejercicios de pilates. Descubre nuestras m\u00e1quinas para pilates y como llegar a un nuevo nivel en pilates.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bonpilates.com\/nl\/torres\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonpilates\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bonpilates.com\/wp-content\/uploads\/2025\/05\/blog-post-2.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"760\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/torres\\\/\",\"url\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/torres\\\/\",\"name\":\"Torres y unidades de pared pilates - Comprar online - Bonpilates\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/#website\"},\"description\":\"Torres y unidades de pared para ejercicios de pilates. Descubre nuestras m\u00e1quinas para pilates y como llegar a un nuevo nivel en pilates.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/torres\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/torres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Bonpilates\",\"item\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Torres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/\",\"name\":\"Bonpilates\",\"description\":\"Desarrollamos y comercializamos m\u00e1quinas de pilates reformer, equipment, accesorios y otros aparatos ideales para practicar este entrenamiento. Bonpilates presenta a sus clientes soluciones de alta calidad y tecnolog\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/#organization\",\"name\":\"Bonpilates\",\"url\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bonpilates.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/bonpilates-logo-header.png\",\"contentUrl\":\"https:\\\/\\\/www.bonpilates.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/bonpilates-logo-header.png\",\"width\":319,\"height\":54,\"caption\":\"Bonpilates\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bonpilates.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bonpilates\\\/\",\"https:\\\/\\\/www.instagram.com\\\/bonpilatesspain\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/bonpilates\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Torres y unidades de pared pilates - Comprar online - Bonpilates","description":"Torres y unidades de pared para ejercicios de pilates. Descubre nuestras m\u00e1quinas para pilates y como llegar a un nuevo nivel en pilates.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bonpilates.com\/nl\/torres\/","og_locale":"nl_NL","og_type":"article","og_title":"Torres y unidades de pared pilates - Comprar online - Bonpilates","og_description":"Torres y unidades de pared para ejercicios de pilates. Descubre nuestras m\u00e1quinas para pilates y como llegar a un nuevo nivel en pilates.","og_url":"https:\/\/www.bonpilates.com\/nl\/torres\/","og_site_name":"Bonpilates","og_image":[{"width":1300,"height":760,"url":"https:\/\/www.bonpilates.com\/wp-content\/uploads\/2025\/05\/blog-post-2.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.bonpilates.com\/nl\/torres\/","url":"https:\/\/www.bonpilates.com\/nl\/torres\/","name":"Torres y unidades de pared pilates - Comprar online - Bonpilates","isPartOf":{"@id":"https:\/\/www.bonpilates.com\/nl\/#website"},"description":"Torres y unidades de pared para ejercicios de pilates. Descubre nuestras m\u00e1quinas para pilates y como llegar a un nuevo nivel en pilates.","breadcrumb":{"@id":"https:\/\/www.bonpilates.com\/nl\/torres\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bonpilates.com\/nl\/torres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Bonpilates","item":"https:\/\/www.bonpilates.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Torres"}]},{"@type":"WebSite","@id":"https:\/\/www.bonpilates.com\/nl\/#website","url":"https:\/\/www.bonpilates.com\/nl\/","name":"Bonpilates","description":"Desarrollamos y comercializamos m\u00e1quinas de pilates reformer, equipment, accesorios y otros aparatos ideales para practicar este entrenamiento. Bonpilates presenta a sus clientes soluciones de alta calidad y tecnolog\u00eda.","publisher":{"@id":"https:\/\/www.bonpilates.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bonpilates.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.bonpilates.com\/nl\/#organization","name":"Bonpilates","url":"https:\/\/www.bonpilates.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.bonpilates.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.bonpilates.com\/wp-content\/uploads\/2024\/03\/bonpilates-logo-header.png","contentUrl":"https:\/\/www.bonpilates.com\/wp-content\/uploads\/2024\/03\/bonpilates-logo-header.png","width":319,"height":54,"caption":"Bonpilates"},"image":{"@id":"https:\/\/www.bonpilates.com\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bonpilates\/","https:\/\/www.instagram.com\/bonpilatesspain\/","https:\/\/www.youtube.com\/user\/bonpilates\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.bonpilates.com\/nl\/wp-json\/wp\/v2\/product_cat\/1035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bonpilates.com\/nl\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.bonpilates.com\/nl\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.bonpilates.com\/nl\/wp-json\/wp\/v2\/product?product_cat=1035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}